{"id":286,"date":"2021-06-09T17:26:06","date_gmt":"2021-06-09T15:26:06","guid":{"rendered":"https:\/\/cadellarte.ms.decms.eu\/?page_id=286"},"modified":"2025-10-09T11:13:00","modified_gmt":"2025-10-09T09:13:00","slug":"unsere-zimmer","status":"publish","type":"page","link":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/","title":{"rendered":"Unsere Zimmer"},"content":{"rendered":"<p>Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander.<\/p>\n<p>&nbsp;<\/p>\n<p>1 Junior Suite im Erdgeschoss<\/p>\n<p>4 Superior-Zimmer im ersten und zweiten Stock<\/p>\n<p>2 Classic-Zimmer im zweiten Stock<\/p>\n<p>2 Deluxe-Zimmer im ersten und zweiten Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander. &nbsp; 1 Junior Suite im Erdgeschoss 4 Superior-Zimmer im ersten und zweiten Stock 2 Classic-Zimmer im zweiten Stock 2 Deluxe-Zimmer im ersten und zweiten Stock<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"template-rooms.php","meta":{"footnotes":""},"class_list":["post-286","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~<\/title>\n<meta name=\"description\" content=\"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander.  &nbsp;  1 Junior Suite im Erdgeschoss  4 Superior-Zimmer im ersten und zweiten Stock  2 Classic-Zimmer im zweiten Stock  2 Deluxe-Zimmer im ersten und zweiten Stock\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~\" \/>\n<meta property=\"og:description\" content=\"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander.  &nbsp;  1 Junior Suite im Erdgeschoss  4 Superior-Zimmer im ersten und zweiten Stock  2 Classic-Zimmer im zweiten Stock  2 Deluxe-Zimmer im ersten und zweiten Stock\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/\" \/>\n<meta property=\"og:site_name\" content=\"Ca\u2019 dell\u2019Arte\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T09:13:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/\",\"url\":\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/\",\"name\":\"Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~\",\"isPartOf\":{\"@id\":\"https:\/\/www.cadellarte.com\/de\/#website\"},\"datePublished\":\"2021-06-09T15:26:06+00:00\",\"dateModified\":\"2025-10-09T09:13:00+00:00\",\"description\":\"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander. &nbsp; 1 Junior Suite im Erdgeschoss 4 Superior-Zimmer im ersten und zweiten Stock 2 Classic-Zimmer im zweiten Stock 2 Deluxe-Zimmer im ersten und zweiten Stock\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cadellarte.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Zimmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cadellarte.com\/de\/#website\",\"url\":\"https:\/\/www.cadellarte.com\/de\/\",\"name\":\"Ca\u2019 dell\u2019Arte\",\"description\":\"Ecco un altro sito ms.decms.eu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cadellarte.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~","description":"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander.  &nbsp;  1 Junior Suite im Erdgeschoss  4 Superior-Zimmer im ersten und zweiten Stock  2 Classic-Zimmer im zweiten Stock  2 Deluxe-Zimmer im ersten und zweiten Stock","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~","og_description":"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander.  &nbsp;  1 Junior Suite im Erdgeschoss  4 Superior-Zimmer im ersten und zweiten Stock  2 Classic-Zimmer im zweiten Stock  2 Deluxe-Zimmer im ersten und zweiten Stock","og_url":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/","og_site_name":"Ca\u2019 dell\u2019Arte","article_modified_time":"2025-10-09T09:13:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/","url":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/","name":"Unsere Zimmer ~ Ca\u2019 dell\u2019Arte ~","isPartOf":{"@id":"https:\/\/www.cadellarte.com\/de\/#website"},"datePublished":"2021-06-09T15:26:06+00:00","dateModified":"2025-10-09T09:13:00+00:00","description":"Das Hotel verf\u00fcgt \u00fcber verschiedene Zimmertypen, die sich auf zwei Etagen verteilen (kein Aufzug). Jedes Zimmer erz\u00e4hlt eine Geschichte und hat seinen eigenen Stil, und alle unterscheiden sich voneinander. &nbsp; 1 Junior Suite im Erdgeschoss 4 Superior-Zimmer im ersten und zweiten Stock 2 Classic-Zimmer im zweiten Stock 2 Deluxe-Zimmer im ersten und zweiten Stock","breadcrumb":{"@id":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadellarte.com\/de\/unsere-zimmer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadellarte.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unsere Zimmer"}]},{"@type":"WebSite","@id":"https:\/\/www.cadellarte.com\/de\/#website","url":"https:\/\/www.cadellarte.com\/de\/","name":"Ca\u2019 dell\u2019Arte","description":"Ecco un altro sito ms.decms.eu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadellarte.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/pages\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":0,"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/pages\/286\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cadellarte.com\/de\/wp-json\/wp\/v2\/media?parent=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}